{"id":5048,"date":"2020-09-01T14:07:16","date_gmt":"2020-09-01T04:07:16","guid":{"rendered":"https:\/\/bloeckerblog.com\/index.php\/2020\/09\/01\/wolfgang-herrndorf\/"},"modified":"2020-09-01T14:12:04","modified_gmt":"2020-09-01T04:12:04","slug":"wolfgang-herrndorf","status":"publish","type":"post","link":"https:\/\/bloeckerblog.com\/index.php\/2020\/09\/01\/wolfgang-herrndorf\/","title":{"rendered":"Wolfgang Herrndorf"},"content":{"rendered":"<p><a href=\"https:\/\/www.ueberwolfgang.de\/#Schriftsteller\">www.ueberwolfgang.de\/<\/a><\/p>\n<p>Diese Seite ist dem Schriftsteller Herrndorf gewidmet, sein Leben, sein Werk und sein fruehes Sterben.<\/p>\n<p>Auch ein Link zu <a href=\"https:\/\/www.wolfgang-herrndorf.de\/2010\/04\/daemmerung\/\" target=\"_blank\" rel=\"noopener noreferrer\">Arbeit und Struktur<\/a>.<\/p>\n<p>Best yours<\/p>\n<p>phb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>www.ueberwolfgang.de\/ Diese Seite ist dem Schriftsteller Herrndorf gewidmet, sein Leben, sein Werk und sein fruehes Sterben. Auch ein Link zu Arbeit und Struktur. Best yours phb<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_crdt_document":"","jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[35],"tags":[1162,657,1161],"class_list":["post-5048","post","type-post","status-publish","format-standard","hentry","category-education","tag-arbeit-und-struktur","tag-literatur","tag-wolfgang-herrndorf"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wolfgang Herrndorf - Bloecker Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bloeckerblog.com\/index.php\/2020\/09\/01\/wolfgang-herrndorf\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"en_US\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Wolfgang Herrndorf - Bloecker Blog\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"www.ueberwolfgang.de\/ Diese Seite ist dem Schriftsteller Herrndorf gewidmet, sein Leben, sein Werk und sein fruehes Sterben. Auch ein Link zu Arbeit und Struktur. Best yours phb\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bloeckerblog.com\/index.php\/2020\/09\/01\/wolfgang-herrndorf\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Bloecker Blog\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/peter.bloecker\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:author\" content=\"https:\/\/facebook.com\/peter.bloecker\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-01T04:07:16+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-01T04:12:04+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"phb\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"phb\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bloeckerblog.com\\\/index.php\\\/2020\\\/09\\\/01\\\/wolfgang-herrndorf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bloeckerblog.com\\\/index.php\\\/2020\\\/09\\\/01\\\/wolfgang-herrndorf\\\/\"},\"author\":{\"name\":\"phb\",\"@id\":\"https:\\\/\\\/bloeckerblog.com\\\/#\\\/schema\\\/person\\\/2835e1821aacb4f0c6f86abbb0e96093\"},\"headline\":\"Wolfgang Herrndorf\",\"datePublished\":\"2020-09-01T04:07:16+00:00\",\"dateModified\":\"2020-09-01T04:12:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bloeckerblog.com\\\/index.php\\\/2020\\\/09\\\/01\\\/wolfgang-herrndorf\\\/\"},\"wordCount\":30,\"publisher\":{\"@id\":\"https:\\\/\\\/bloeckerblog.com\\\/#\\\/schema\\\/person\\\/2835e1821aacb4f0c6f86abbb0e96093\"},\"keywords\":[\"Arbeit und Struktur\",\"Literatur\",\"Wolfgang Herrndorf\"],\"articleSection\":[\"Education\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bloeckerblog.com\\\/index.php\\\/2020\\\/09\\\/01\\\/wolfgang-herrndorf\\\/\",\"url\":\"https:\\\/\\\/bloeckerblog.com\\\/index.php\\\/2020\\\/09\\\/01\\\/wolfgang-herrndorf\\\/\",\"name\":\"Wolfgang Herrndorf - Bloecker Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bloeckerblog.com\\\/#website\"},\"datePublished\":\"2020-09-01T04:07:16+00:00\",\"dateModified\":\"2020-09-01T04:12:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bloeckerblog.com\\\/index.php\\\/2020\\\/09\\\/01\\\/wolfgang-herrndorf\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bloeckerblog.com\\\/index.php\\\/2020\\\/09\\\/01\\\/wolfgang-herrndorf\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bloeckerblog.com\\\/index.php\\\/2020\\\/09\\\/01\\\/wolfgang-herrndorf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bloeckerblog.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wolfgang Herrndorf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bloeckerblog.com\\\/#website\",\"url\":\"https:\\\/\\\/bloeckerblog.com\\\/\",\"name\":\"Bloecker Blog\",\"description\":\"Blogging on Higher Education\",\"publisher\":{\"@id\":\"https:\\\/\\\/bloeckerblog.com\\\/#\\\/schema\\\/person\\\/2835e1821aacb4f0c6f86abbb0e96093\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bloeckerblog.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/bloeckerblog.com\\\/#\\\/schema\\\/person\\\/2835e1821aacb4f0c6f86abbb0e96093\",\"name\":\"phb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/bloeckerblog.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/avatar_original-1-1.jpg?fit=500%2C500&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/bloeckerblog.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/avatar_original-1-1.jpg?fit=500%2C500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/bloeckerblog.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/avatar_original-1-1.jpg?fit=500%2C500&ssl=1\",\"width\":500,\"height\":500,\"caption\":\"phb\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/bloeckerblog.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/avatar_original-1-1.jpg?fit=500%2C500&ssl=1\"},\"description\":\"Linguist plus Educator of English and German and American Studies, retired since AUG 2015. Teacher at the DHPS Windhoek, Namibia, from 1988-2004. Living at the Gold Coast in QLD Australia with Casa Da Vovo Burleigh (FB). German Language Adviser of the Goethe-Institut Sydney (1998 - 2005) Office in Brisbane, Education QUEENSLAND. Coordinator and Director of Studies at Fritz Reuter Gymnasium, Dannenberg (River Elbe) from 2005 - 2012. (ATZ) Active Blogger and Digital Nomad. Author of Business German Podcast on Spotify.com Gymnasium Blogger Germany Author on Medium.com Truly Northern Music Is The LANGUAGE\",\"sameAs\":[\"https:\\\/\\\/peblogger.com\",\"https:\\\/\\\/facebook.com\\\/peter.bloecker\",\"https:\\\/\\\/instagram.com\\\/peblogger\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wolfgang Herrndorf - Bloecker Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bloeckerblog.com\/index.php\/2020\/09\/01\/wolfgang-herrndorf\/","og_locale":"en_US","og_type":"article","og_title":"Wolfgang Herrndorf - Bloecker Blog","og_description":"www.ueberwolfgang.de\/ Diese Seite ist dem Schriftsteller Herrndorf gewidmet, sein Leben, sein Werk und sein fruehes Sterben. Auch ein Link zu Arbeit und Struktur. Best yours phb","og_url":"https:\/\/bloeckerblog.com\/index.php\/2020\/09\/01\/wolfgang-herrndorf\/","og_site_name":"Bloecker Blog","article_publisher":"https:\/\/facebook.com\/peter.bloecker","article_author":"https:\/\/facebook.com\/peter.bloecker","article_published_time":"2020-09-01T04:07:16+00:00","article_modified_time":"2020-09-01T04:12:04+00:00","author":"phb","twitter_card":"summary_large_image","twitter_misc":{"Written by":"phb"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bloeckerblog.com\/index.php\/2020\/09\/01\/wolfgang-herrndorf\/#article","isPartOf":{"@id":"https:\/\/bloeckerblog.com\/index.php\/2020\/09\/01\/wolfgang-herrndorf\/"},"author":{"name":"phb","@id":"https:\/\/bloeckerblog.com\/#\/schema\/person\/2835e1821aacb4f0c6f86abbb0e96093"},"headline":"Wolfgang Herrndorf","datePublished":"2020-09-01T04:07:16+00:00","dateModified":"2020-09-01T04:12:04+00:00","mainEntityOfPage":{"@id":"https:\/\/bloeckerblog.com\/index.php\/2020\/09\/01\/wolfgang-herrndorf\/"},"wordCount":30,"publisher":{"@id":"https:\/\/bloeckerblog.com\/#\/schema\/person\/2835e1821aacb4f0c6f86abbb0e96093"},"keywords":["Arbeit und Struktur","Literatur","Wolfgang Herrndorf"],"articleSection":["Education"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/bloeckerblog.com\/index.php\/2020\/09\/01\/wolfgang-herrndorf\/","url":"https:\/\/bloeckerblog.com\/index.php\/2020\/09\/01\/wolfgang-herrndorf\/","name":"Wolfgang Herrndorf - Bloecker Blog","isPartOf":{"@id":"https:\/\/bloeckerblog.com\/#website"},"datePublished":"2020-09-01T04:07:16+00:00","dateModified":"2020-09-01T04:12:04+00:00","breadcrumb":{"@id":"https:\/\/bloeckerblog.com\/index.php\/2020\/09\/01\/wolfgang-herrndorf\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bloeckerblog.com\/index.php\/2020\/09\/01\/wolfgang-herrndorf\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bloeckerblog.com\/index.php\/2020\/09\/01\/wolfgang-herrndorf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bloeckerblog.com\/"},{"@type":"ListItem","position":2,"name":"Wolfgang Herrndorf"}]},{"@type":"WebSite","@id":"https:\/\/bloeckerblog.com\/#website","url":"https:\/\/bloeckerblog.com\/","name":"Bloecker Blog","description":"Blogging on Higher Education","publisher":{"@id":"https:\/\/bloeckerblog.com\/#\/schema\/person\/2835e1821aacb4f0c6f86abbb0e96093"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bloeckerblog.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/bloeckerblog.com\/#\/schema\/person\/2835e1821aacb4f0c6f86abbb0e96093","name":"phb","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/bloeckerblog.com\/wp-content\/uploads\/2024\/03\/avatar_original-1-1.jpg?fit=500%2C500&ssl=1","url":"https:\/\/i0.wp.com\/bloeckerblog.com\/wp-content\/uploads\/2024\/03\/avatar_original-1-1.jpg?fit=500%2C500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/bloeckerblog.com\/wp-content\/uploads\/2024\/03\/avatar_original-1-1.jpg?fit=500%2C500&ssl=1","width":500,"height":500,"caption":"phb"},"logo":{"@id":"https:\/\/i0.wp.com\/bloeckerblog.com\/wp-content\/uploads\/2024\/03\/avatar_original-1-1.jpg?fit=500%2C500&ssl=1"},"description":"Linguist plus Educator of English and German and American Studies, retired since AUG 2015. Teacher at the DHPS Windhoek, Namibia, from 1988-2004. Living at the Gold Coast in QLD Australia with Casa Da Vovo Burleigh (FB). German Language Adviser of the Goethe-Institut Sydney (1998 - 2005) Office in Brisbane, Education QUEENSLAND. Coordinator and Director of Studies at Fritz Reuter Gymnasium, Dannenberg (River Elbe) from 2005 - 2012. (ATZ) Active Blogger and Digital Nomad. Author of Business German Podcast on Spotify.com Gymnasium Blogger Germany Author on Medium.com Truly Northern Music Is The LANGUAGE","sameAs":["https:\/\/peblogger.com","https:\/\/facebook.com\/peter.bloecker","https:\/\/instagram.com\/peblogger"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pchfmT-1jq","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bloeckerblog.com\/index.php\/wp-json\/wp\/v2\/posts\/5048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bloeckerblog.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bloeckerblog.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bloeckerblog.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bloeckerblog.com\/index.php\/wp-json\/wp\/v2\/comments?post=5048"}],"version-history":[{"count":0,"href":"https:\/\/bloeckerblog.com\/index.php\/wp-json\/wp\/v2\/posts\/5048\/revisions"}],"wp:attachment":[{"href":"https:\/\/bloeckerblog.com\/index.php\/wp-json\/wp\/v2\/media?parent=5048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bloeckerblog.com\/index.php\/wp-json\/wp\/v2\/categories?post=5048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bloeckerblog.com\/index.php\/wp-json\/wp\/v2\/tags?post=5048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}